{"id":12189,"date":"2013-07-19T05:00:07","date_gmt":"2013-07-19T03:00:07","guid":{"rendered":"https:\/\/donnarossa.ch\/fo-which-came-first-egg-or-chicken\/"},"modified":"2013-07-19T05:00:07","modified_gmt":"2013-07-19T03:00:07","slug":"fo-which-came-first-egg-or-chicken","status":"publish","type":"post","link":"https:\/\/donnarossa.ch\/de\/fo-which-came-first-egg-or-chicken\/","title":{"rendered":"FO &#8211; Which came first, egg or chicken?"},"content":{"rendered":"<p><a href=\"https:\/\/donnarossa.ch\/wordpress\/wp-content\/uploads\/2013\/07\/which-came-first-collage-wide.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-1131\" src=\"https:\/\/donnarossa.ch\/wordpress\/wp-content\/uploads\/2013\/07\/which-came-first-collage-wide.jpg\" alt=\"which came first\" width=\"1200\" height=\"1200\" \/><\/a>After making <a href=\"http:\/\/www.ravelry.com\/projects\/donnarossa\/mauritius-dodo\" target=\"_blank\" rel=\"noopener noreferrer\">Dodo&#8217;s<\/a>, <a href=\"http:\/\/www.ravelry.com\/projects\/donnarossa\/elefante\" target=\"_blank\" rel=\"noopener noreferrer\">Elephant <\/a>and <a href=\"http:\/\/www.ravelry.com\/projects\/donnarossa\/frida-the-fish\" target=\"_blank\" rel=\"noopener noreferrer\">Fish <\/a>toys I want to do something different. For a friends newborn I made this <del>little<\/del> funny toy. It&#8217;s name is &#8222;<a href=\"http:\/\/www.ravelry.com\/projects\/donnarossa\/which-came-first\" target=\"_blank\" rel=\"noopener noreferrer\">Which came first<\/a>&#8220; and it&#8217;s big like an ostrich egg. You can turn it inside out; whatever you like.<\/p>\n<p>I love to make knitted or crocheted toys for babys. (Sometimes the daddies have even more fun to play with.) But making toys tend to be very fiddly and\/or a lot of sewing. On the other hand you can use up some leftovers. And gauge is not important, but if you combine two different yarns, you should do it. Guess how I recognize that point. I&#8217;ve used for the egg a different yarn. I thought it was the same weight and started to knit with until I run out of yarn after doing 80% of the egg. Later I recognized the difference and started over with the egg.<\/p>\n<p>By the end it&#8217;s always fun to see the result and I hope the newborn has fun with it too. My boyfriend thinks it looks funny but somehow it makes him confused. Are you confused too? How do you like it? I would love to hear what you think about it.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>After making Dodo&#8217;s, Elephant and Fish toys I want to do something different. For a friends newborn I made this little funny toy. It&#8217;s name is &#8222;Which came first&#8220; and &hellip; <a class=\"kt-excerpt-readmore\" href=\"https:\/\/donnarossa.ch\/de\/fo-which-came-first-egg-or-chicken\/\" aria-label=\"FO &#8211; Which came first, egg or chicken?\">Weiterlesen<\/a><\/p>\n","protected":false},"author":2,"featured_media":12486,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[300],"tags":[],"class_list":["post-12189","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fertige-objekte"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>FO - Which came first, egg or chicken? \u2013 DONNAROSSA<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/donnarossa.ch\/de\/fo-which-came-first-egg-or-chicken\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"FO - Which came first, egg or chicken? \u2013 DONNAROSSA\" \/>\n<meta property=\"og:description\" content=\"After making Dodo&#8217;s, Elephant and Fish toys I want to do something different. For a friends newborn I made this little funny toy. It&#8217;s name is &#8222;Which came first&#8220; and &hellip; Weiterlesen\" \/>\n<meta property=\"og:url\" content=\"https:\/\/donnarossa.ch\/de\/fo-which-came-first-egg-or-chicken\/\" \/>\n<meta property=\"og:site_name\" content=\"DONNAROSSA\" \/>\n<meta property=\"article:published_time\" content=\"2013-07-19T03:00:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/donnarossa.ch\/wordpress\/wp-content\/uploads\/2013\/07\/which-came-first-collage-wide-e1548610315389.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"donnarossa\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"donnarossa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/donnarossa.ch\\\/de\\\/fo-which-came-first-egg-or-chicken\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/donnarossa.ch\\\/de\\\/fo-which-came-first-egg-or-chicken\\\/\"},\"author\":{\"name\":\"donnarossa\",\"@id\":\"https:\\\/\\\/donnarossa.ch\\\/de\\\/#\\\/schema\\\/person\\\/84a2f974884e7e0a05415f057edb3991\"},\"headline\":\"FO &#8211; Which came first, egg or chicken?\",\"datePublished\":\"2013-07-19T03:00:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/donnarossa.ch\\\/de\\\/fo-which-came-first-egg-or-chicken\\\/\"},\"wordCount\":217,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/donnarossa.ch\\\/de\\\/#\\\/schema\\\/person\\\/84a2f974884e7e0a05415f057edb3991\"},\"image\":{\"@id\":\"https:\\\/\\\/donnarossa.ch\\\/de\\\/fo-which-came-first-egg-or-chicken\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/donnarossa.ch\\\/wordpress\\\/wp-content\\\/uploads\\\/2013\\\/07\\\/which-came-first-collage-wide-e1548610315389.jpg\",\"articleSection\":[\"Fertige Objekte\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/donnarossa.ch\\\/de\\\/fo-which-came-first-egg-or-chicken\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/donnarossa.ch\\\/de\\\/fo-which-came-first-egg-or-chicken\\\/\",\"url\":\"https:\\\/\\\/donnarossa.ch\\\/de\\\/fo-which-came-first-egg-or-chicken\\\/\",\"name\":\"FO - Which came first, egg or chicken? \u2013 DONNAROSSA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/donnarossa.ch\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/donnarossa.ch\\\/de\\\/fo-which-came-first-egg-or-chicken\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/donnarossa.ch\\\/de\\\/fo-which-came-first-egg-or-chicken\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/donnarossa.ch\\\/wordpress\\\/wp-content\\\/uploads\\\/2013\\\/07\\\/which-came-first-collage-wide-e1548610315389.jpg\",\"datePublished\":\"2013-07-19T03:00:07+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/donnarossa.ch\\\/de\\\/fo-which-came-first-egg-or-chicken\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/donnarossa.ch\\\/de\\\/fo-which-came-first-egg-or-chicken\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/donnarossa.ch\\\/de\\\/fo-which-came-first-egg-or-chicken\\\/#primaryimage\",\"url\":\"https:\\\/\\\/donnarossa.ch\\\/wordpress\\\/wp-content\\\/uploads\\\/2013\\\/07\\\/which-came-first-collage-wide-e1548610315389.jpg\",\"contentUrl\":\"https:\\\/\\\/donnarossa.ch\\\/wordpress\\\/wp-content\\\/uploads\\\/2013\\\/07\\\/which-came-first-collage-wide-e1548610315389.jpg\",\"width\":1000,\"height\":1000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/donnarossa.ch\\\/de\\\/fo-which-came-first-egg-or-chicken\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/donnarossa.ch\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"FO &#8211; Which came first, egg or chicken?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/donnarossa.ch\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/donnarossa.ch\\\/de\\\/\",\"name\":\"DONNAROSSA\",\"description\":\"Strickanleitungen &amp; Workshops f\u00fcr die moderne Macherin\",\"publisher\":{\"@id\":\"https:\\\/\\\/donnarossa.ch\\\/de\\\/#\\\/schema\\\/person\\\/84a2f974884e7e0a05415f057edb3991\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/donnarossa.ch\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/donnarossa.ch\\\/de\\\/#\\\/schema\\\/person\\\/84a2f974884e7e0a05415f057edb3991\",\"name\":\"donnarossa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/donnarossa.ch\\\/wordpress\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/Portrait-quadrat.jpg\",\"url\":\"https:\\\/\\\/donnarossa.ch\\\/wordpress\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/Portrait-quadrat.jpg\",\"contentUrl\":\"https:\\\/\\\/donnarossa.ch\\\/wordpress\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/Portrait-quadrat.jpg\",\"width\":1000,\"height\":1000,\"caption\":\"donnarossa\"},\"logo\":{\"@id\":\"https:\\\/\\\/donnarossa.ch\\\/wordpress\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/Portrait-quadrat.jpg\"},\"url\":\"https:\\\/\\\/donnarossa.ch\\\/de\\\/author\\\/donnarossa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"FO - Which came first, egg or chicken? \u2013 DONNAROSSA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/donnarossa.ch\/de\/fo-which-came-first-egg-or-chicken\/","og_locale":"de_DE","og_type":"article","og_title":"FO - Which came first, egg or chicken? \u2013 DONNAROSSA","og_description":"After making Dodo&#8217;s, Elephant and Fish toys I want to do something different. For a friends newborn I made this little funny toy. It&#8217;s name is &#8222;Which came first&#8220; and &hellip; Weiterlesen","og_url":"https:\/\/donnarossa.ch\/de\/fo-which-came-first-egg-or-chicken\/","og_site_name":"DONNAROSSA","article_published_time":"2013-07-19T03:00:07+00:00","og_image":[{"width":1000,"height":1000,"url":"https:\/\/donnarossa.ch\/wordpress\/wp-content\/uploads\/2013\/07\/which-came-first-collage-wide-e1548610315389.jpg","type":"image\/jpeg"}],"author":"donnarossa","twitter_misc":{"Verfasst von":"donnarossa","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/donnarossa.ch\/de\/fo-which-came-first-egg-or-chicken\/#article","isPartOf":{"@id":"https:\/\/donnarossa.ch\/de\/fo-which-came-first-egg-or-chicken\/"},"author":{"name":"donnarossa","@id":"https:\/\/donnarossa.ch\/de\/#\/schema\/person\/84a2f974884e7e0a05415f057edb3991"},"headline":"FO &#8211; Which came first, egg or chicken?","datePublished":"2013-07-19T03:00:07+00:00","mainEntityOfPage":{"@id":"https:\/\/donnarossa.ch\/de\/fo-which-came-first-egg-or-chicken\/"},"wordCount":217,"commentCount":0,"publisher":{"@id":"https:\/\/donnarossa.ch\/de\/#\/schema\/person\/84a2f974884e7e0a05415f057edb3991"},"image":{"@id":"https:\/\/donnarossa.ch\/de\/fo-which-came-first-egg-or-chicken\/#primaryimage"},"thumbnailUrl":"https:\/\/donnarossa.ch\/wordpress\/wp-content\/uploads\/2013\/07\/which-came-first-collage-wide-e1548610315389.jpg","articleSection":["Fertige Objekte"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/donnarossa.ch\/de\/fo-which-came-first-egg-or-chicken\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/donnarossa.ch\/de\/fo-which-came-first-egg-or-chicken\/","url":"https:\/\/donnarossa.ch\/de\/fo-which-came-first-egg-or-chicken\/","name":"FO - Which came first, egg or chicken? \u2013 DONNAROSSA","isPartOf":{"@id":"https:\/\/donnarossa.ch\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/donnarossa.ch\/de\/fo-which-came-first-egg-or-chicken\/#primaryimage"},"image":{"@id":"https:\/\/donnarossa.ch\/de\/fo-which-came-first-egg-or-chicken\/#primaryimage"},"thumbnailUrl":"https:\/\/donnarossa.ch\/wordpress\/wp-content\/uploads\/2013\/07\/which-came-first-collage-wide-e1548610315389.jpg","datePublished":"2013-07-19T03:00:07+00:00","breadcrumb":{"@id":"https:\/\/donnarossa.ch\/de\/fo-which-came-first-egg-or-chicken\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/donnarossa.ch\/de\/fo-which-came-first-egg-or-chicken\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/donnarossa.ch\/de\/fo-which-came-first-egg-or-chicken\/#primaryimage","url":"https:\/\/donnarossa.ch\/wordpress\/wp-content\/uploads\/2013\/07\/which-came-first-collage-wide-e1548610315389.jpg","contentUrl":"https:\/\/donnarossa.ch\/wordpress\/wp-content\/uploads\/2013\/07\/which-came-first-collage-wide-e1548610315389.jpg","width":1000,"height":1000},{"@type":"BreadcrumbList","@id":"https:\/\/donnarossa.ch\/de\/fo-which-came-first-egg-or-chicken\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/donnarossa.ch\/de\/"},{"@type":"ListItem","position":2,"name":"FO &#8211; Which came first, egg or chicken?"}]},{"@type":"WebSite","@id":"https:\/\/donnarossa.ch\/de\/#website","url":"https:\/\/donnarossa.ch\/de\/","name":"DONNAROSSA","description":"Strickanleitungen &amp; Workshops f\u00fcr die moderne Macherin","publisher":{"@id":"https:\/\/donnarossa.ch\/de\/#\/schema\/person\/84a2f974884e7e0a05415f057edb3991"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/donnarossa.ch\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":["Person","Organization"],"@id":"https:\/\/donnarossa.ch\/de\/#\/schema\/person\/84a2f974884e7e0a05415f057edb3991","name":"donnarossa","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/donnarossa.ch\/wordpress\/wp-content\/uploads\/2021\/04\/Portrait-quadrat.jpg","url":"https:\/\/donnarossa.ch\/wordpress\/wp-content\/uploads\/2021\/04\/Portrait-quadrat.jpg","contentUrl":"https:\/\/donnarossa.ch\/wordpress\/wp-content\/uploads\/2021\/04\/Portrait-quadrat.jpg","width":1000,"height":1000,"caption":"donnarossa"},"logo":{"@id":"https:\/\/donnarossa.ch\/wordpress\/wp-content\/uploads\/2021\/04\/Portrait-quadrat.jpg"},"url":"https:\/\/donnarossa.ch\/de\/author\/donnarossa\/"}]}},"_links":{"self":[{"href":"https:\/\/donnarossa.ch\/de\/wp-json\/wp\/v2\/posts\/12189","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/donnarossa.ch\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/donnarossa.ch\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/donnarossa.ch\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/donnarossa.ch\/de\/wp-json\/wp\/v2\/comments?post=12189"}],"version-history":[{"count":0,"href":"https:\/\/donnarossa.ch\/de\/wp-json\/wp\/v2\/posts\/12189\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/donnarossa.ch\/de\/wp-json\/wp\/v2\/media\/12486"}],"wp:attachment":[{"href":"https:\/\/donnarossa.ch\/de\/wp-json\/wp\/v2\/media?parent=12189"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/donnarossa.ch\/de\/wp-json\/wp\/v2\/categories?post=12189"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/donnarossa.ch\/de\/wp-json\/wp\/v2\/tags?post=12189"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}