{"id":12258,"date":"2016-12-04T11:50:14","date_gmt":"2016-12-04T09:50:14","guid":{"rendered":"https:\/\/donnarossa.ch\/mein-erster-auftrag-eine-mutze-fur-den-bundesrat\/"},"modified":"2016-12-04T11:50:14","modified_gmt":"2016-12-04T09:50:14","slug":"mein-erster-auftrag-eine-mutze-fur-den-bundesrat","status":"publish","type":"post","link":"https:\/\/donnarossa.ch\/de\/mein-erster-auftrag-eine-mutze-fur-den-bundesrat\/","title":{"rendered":"Mein erster Auftrag: eine M\u00fctze f\u00fcr den Bundesrat"},"content":{"rendered":"<h4>Wo findet man eine M\u00fctze mit einem speziellen Motiv? L\u00e4sst man das Motiv professionell sticken? Oder die M\u00fctze sogar bedrucken? Hier zeigen sich die Vorteile von Handgemachtem: Man kann das St\u00fcck auf die Gr\u00f6sse, Farben sowie Motive individuell gestalten.<\/h4>\n<p>Als meine Freundin mit diesem speziellen Wunsch auf mich zugekommen ist, war ich ziemlich \u00fcberrascht. Gesucht war eine M\u00fctze mit der Schweizer und Schwedischen Fahne.<\/p>\n<p>Ohne zu wissen wie gross der Kopfumfang ist, hab ich mich in das Projekt gest\u00fcrzt. Damit das Motiv nicht zu grob wird, habe ich mich f\u00fcr ein d\u00fcnnes (fingering weight) Garn entschieden. Nach einer Maschenprobe habe ich die M\u00fctze berechnet.<\/p>\n<p>Das Motiv kam vom Auftraggeber. Ich habe das Bild in Photoshop auf f\u00fcnf Farben reduziert: rot, weiss, blau, gelb und schwarz.\u00a0Mit dem Onlinedienst f\u00fcr Strick- und Stickschriften <a href=\"http:\/\/www.microrevolt.org\/knitPro\/\" target=\"_blank\" rel=\"noopener noreferrer\">Microrevolt Knit Pro<\/a> habe ich\u00a0die Motivgr\u00f6sse gepr\u00fcft.\u00a0Bei dieser Seite kann man ein Bild hochladen und es berechnet dies in eine Strick- oder Stickschrift.<\/p>\n<p>Das B\u00fcndchen wurde im Rippenmuster (1 rechts, 1 links) in der Runde gestrickt. Danach wurde das Motiv in glatt rechts als Intarsia gestrickt.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-5731\" src=\"https:\/\/donnarossa.ch\/wordpress\/wp-content\/uploads\/2016\/11\/WASA-hat.jpg\" alt=\"wasa hat stricken m\u00fctze knit\" width=\"1000\" height=\"667\" srcset=\"https:\/\/donnarossa.ch\/wordpress\/wp-content\/uploads\/2016\/11\/WASA-hat.jpg 1000w, https:\/\/donnarossa.ch\/wordpress\/wp-content\/uploads\/2016\/11\/WASA-hat-150x100.jpg 150w, https:\/\/donnarossa.ch\/wordpress\/wp-content\/uploads\/2016\/11\/WASA-hat-500x334.jpg 500w, https:\/\/donnarossa.ch\/wordpress\/wp-content\/uploads\/2016\/11\/WASA-hat-768x512.jpg 768w, https:\/\/donnarossa.ch\/wordpress\/wp-content\/uploads\/2016\/11\/WASA-hat-100x67.jpg 100w, https:\/\/donnarossa.ch\/wordpress\/wp-content\/uploads\/2016\/11\/WASA-hat-272x182.jpg 272w, https:\/\/donnarossa.ch\/wordpress\/wp-content\/uploads\/2016\/11\/WASA-hat-728x486.jpg 728w, https:\/\/donnarossa.ch\/wordpress\/wp-content\/uploads\/2016\/11\/WASA-hat-364x243.jpg 364w, https:\/\/donnarossa.ch\/wordpress\/wp-content\/uploads\/2016\/11\/WASA-hat-520x346.jpg 520w, https:\/\/donnarossa.ch\/wordpress\/wp-content\/uploads\/2016\/11\/WASA-hat-260x173.jpg 260w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/p>\n<p>Zuerst versuchte ich in der Runde Intarsia zu stricken, scheiterte aber damit kl\u00e4glich. Bei Intarsia in der Runde strickt man auch hin und her.\u00a0Durch das Stricken einer R\u00fcckreihe strickt man pl\u00f6tzlich mitten im Gestrickten in einer Reihe dar\u00fcber als im Rest. Schnell hab ich f\u00fcr mich fest gestellt, dass das Motiv daf\u00fcr zu komplex war. Also zur\u00fcck zum Anfang.<\/p>\n<p>Ich habe auf der Hinterseite der M\u00fctze einen Schlitz gemacht, damit ich Intarsia in Hin- und R\u00fcckreihen stricken kann. Bevor die Krone gestrickt wurde, habe ich den Schlitz wieder geschlossen und weiter in Runden gestrickt. Am Schluss wurde der Schlitz mit dem Matratzenstich geschlossen.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-5730 size-full\" src=\"https:\/\/donnarossa.ch\/wordpress\/wp-content\/uploads\/2016\/11\/WASA-hat-inside-name-tag.jpg\" alt=\"wasa-hat-inside-name-tag\" width=\"1000\" height=\"667\" srcset=\"https:\/\/donnarossa.ch\/wordpress\/wp-content\/uploads\/2016\/11\/WASA-hat-inside-name-tag.jpg 1000w, https:\/\/donnarossa.ch\/wordpress\/wp-content\/uploads\/2016\/11\/WASA-hat-inside-name-tag-150x100.jpg 150w, https:\/\/donnarossa.ch\/wordpress\/wp-content\/uploads\/2016\/11\/WASA-hat-inside-name-tag-300x200.jpg 300w, https:\/\/donnarossa.ch\/wordpress\/wp-content\/uploads\/2016\/11\/WASA-hat-inside-name-tag-500x334.jpg 500w, https:\/\/donnarossa.ch\/wordpress\/wp-content\/uploads\/2016\/11\/WASA-hat-inside-name-tag-768x512.jpg 768w, https:\/\/donnarossa.ch\/wordpress\/wp-content\/uploads\/2016\/11\/WASA-hat-inside-name-tag-100x67.jpg 100w, https:\/\/donnarossa.ch\/wordpress\/wp-content\/uploads\/2016\/11\/WASA-hat-inside-name-tag-272x182.jpg 272w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/p>\n<p>Und eines meiner neuer Labels (bestellt bei <a href=\"http:\/\/www.dortex.ch\/\" target=\"_blank\" rel=\"noopener noreferrer\">Dortex<\/a>) durfte nicht fehlen..<\/p>\n<figure id=\"attachment_5732\" class=\"thumbnail wp-caption aligncenter\" style=\"width: 1000px\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-5732\" src=\"https:\/\/donnarossa.ch\/wordpress\/wp-content\/uploads\/2016\/11\/\u00dcbergabe-M\u00fctze.jpg\" alt=\"wasa hat stricken knit m\u00fctze\" width=\"1000\" height=\"667\" srcset=\"https:\/\/donnarossa.ch\/wordpress\/wp-content\/uploads\/2016\/11\/\u00dcbergabe-M\u00fctze.jpg 1000w, https:\/\/donnarossa.ch\/wordpress\/wp-content\/uploads\/2016\/11\/\u00dcbergabe-M\u00fctze-150x100.jpg 150w, https:\/\/donnarossa.ch\/wordpress\/wp-content\/uploads\/2016\/11\/\u00dcbergabe-M\u00fctze-300x200.jpg 300w, https:\/\/donnarossa.ch\/wordpress\/wp-content\/uploads\/2016\/11\/\u00dcbergabe-M\u00fctze-500x334.jpg 500w, https:\/\/donnarossa.ch\/wordpress\/wp-content\/uploads\/2016\/11\/\u00dcbergabe-M\u00fctze-768x512.jpg 768w, https:\/\/donnarossa.ch\/wordpress\/wp-content\/uploads\/2016\/11\/\u00dcbergabe-M\u00fctze-100x67.jpg 100w, https:\/\/donnarossa.ch\/wordpress\/wp-content\/uploads\/2016\/11\/\u00dcbergabe-M\u00fctze-272x182.jpg 272w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><figcaption class=\"caption wp-caption-text\">Tag der Wirtschaft in der St.Jakobshalle am Donnerstag, 25. November 2016 in Muttenz . \u00a9 Photo Dominik Pluess<\/figcaption><\/figure>\n<p>An einem Wirtschaftsanlass Ende November wurde die M\u00fctze dem Bundesrat Ueli Maurer \u00fcberreicht.<\/p>\n<p>Ein Journalist der Basler Zeitung griff die M\u00fctze in <a href=\"http:\/\/bazonline.ch\/schweiz\/standard\/unsinn-und-wahnsinn\/story\/11300098\" target=\"_blank\" rel=\"noopener noreferrer\">seinem Artikel<\/a> auf.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wo findet man eine M\u00fctze mit einem speziellen Motiv? L\u00e4sst man das Motiv professionell sticken? Oder die M\u00fctze sogar bedrucken? Hier zeigen sich die Vorteile von Handgemachtem: Man kann das &hellip; <a class=\"kt-excerpt-readmore\" href=\"https:\/\/donnarossa.ch\/de\/mein-erster-auftrag-eine-mutze-fur-den-bundesrat\/\" aria-label=\"Mein erster Auftrag: eine M\u00fctze f\u00fcr den Bundesrat\">Weiterlesen<\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[300],"tags":[],"class_list":["post-12258","post","type-post","status-publish","format-standard","hentry","category-fertige-objekte"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mein erster Auftrag: eine M\u00fctze f\u00fcr den Bundesrat \u2013 DONNAROSSA<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/donnarossa.ch\/de\/mein-erster-auftrag-eine-mutze-fur-den-bundesrat\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mein erster Auftrag: eine M\u00fctze f\u00fcr den Bundesrat \u2013 DONNAROSSA\" \/>\n<meta property=\"og:description\" content=\"Wo findet man eine M\u00fctze mit einem speziellen Motiv? L\u00e4sst man das Motiv professionell sticken? Oder die M\u00fctze sogar bedrucken? Hier zeigen sich die Vorteile von Handgemachtem: Man kann das &hellip; Weiterlesen\" \/>\n<meta property=\"og:url\" content=\"https:\/\/donnarossa.ch\/de\/mein-erster-auftrag-eine-mutze-fur-den-bundesrat\/\" \/>\n<meta property=\"og:site_name\" content=\"DONNAROSSA\" \/>\n<meta property=\"article:published_time\" content=\"2016-12-04T09:50:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/donnarossa.ch\/wordpress\/wp-content\/uploads\/2016\/11\/WASA-hat.jpg\" \/>\n<meta name=\"author\" content=\"donnarossa\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"donnarossa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/donnarossa.ch\\\/de\\\/mein-erster-auftrag-eine-mutze-fur-den-bundesrat\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/donnarossa.ch\\\/de\\\/mein-erster-auftrag-eine-mutze-fur-den-bundesrat\\\/\"},\"author\":{\"name\":\"donnarossa\",\"@id\":\"https:\\\/\\\/donnarossa.ch\\\/de\\\/#\\\/schema\\\/person\\\/84a2f974884e7e0a05415f057edb3991\"},\"headline\":\"Mein erster Auftrag: eine M\u00fctze f\u00fcr den Bundesrat\",\"datePublished\":\"2016-12-04T09:50:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/donnarossa.ch\\\/de\\\/mein-erster-auftrag-eine-mutze-fur-den-bundesrat\\\/\"},\"wordCount\":376,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/donnarossa.ch\\\/de\\\/#\\\/schema\\\/person\\\/84a2f974884e7e0a05415f057edb3991\"},\"image\":{\"@id\":\"https:\\\/\\\/donnarossa.ch\\\/de\\\/mein-erster-auftrag-eine-mutze-fur-den-bundesrat\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/donnarossa.ch\\\/wordpress\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/WASA-hat.jpg\",\"articleSection\":[\"Fertige Objekte\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/donnarossa.ch\\\/de\\\/mein-erster-auftrag-eine-mutze-fur-den-bundesrat\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/donnarossa.ch\\\/de\\\/mein-erster-auftrag-eine-mutze-fur-den-bundesrat\\\/\",\"url\":\"https:\\\/\\\/donnarossa.ch\\\/de\\\/mein-erster-auftrag-eine-mutze-fur-den-bundesrat\\\/\",\"name\":\"Mein erster Auftrag: eine M\u00fctze f\u00fcr den Bundesrat \u2013 DONNAROSSA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/donnarossa.ch\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/donnarossa.ch\\\/de\\\/mein-erster-auftrag-eine-mutze-fur-den-bundesrat\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/donnarossa.ch\\\/de\\\/mein-erster-auftrag-eine-mutze-fur-den-bundesrat\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/donnarossa.ch\\\/wordpress\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/WASA-hat.jpg\",\"datePublished\":\"2016-12-04T09:50:14+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/donnarossa.ch\\\/de\\\/mein-erster-auftrag-eine-mutze-fur-den-bundesrat\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/donnarossa.ch\\\/de\\\/mein-erster-auftrag-eine-mutze-fur-den-bundesrat\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/donnarossa.ch\\\/de\\\/mein-erster-auftrag-eine-mutze-fur-den-bundesrat\\\/#primaryimage\",\"url\":\"https:\\\/\\\/donnarossa.ch\\\/wordpress\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/WASA-hat.jpg\",\"contentUrl\":\"https:\\\/\\\/donnarossa.ch\\\/wordpress\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/WASA-hat.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/donnarossa.ch\\\/de\\\/mein-erster-auftrag-eine-mutze-fur-den-bundesrat\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/donnarossa.ch\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mein erster Auftrag: eine M\u00fctze f\u00fcr den Bundesrat\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/donnarossa.ch\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/donnarossa.ch\\\/de\\\/\",\"name\":\"DONNAROSSA\",\"description\":\"Strickanleitungen &amp; Workshops f\u00fcr die moderne Macherin\",\"publisher\":{\"@id\":\"https:\\\/\\\/donnarossa.ch\\\/de\\\/#\\\/schema\\\/person\\\/84a2f974884e7e0a05415f057edb3991\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/donnarossa.ch\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/donnarossa.ch\\\/de\\\/#\\\/schema\\\/person\\\/84a2f974884e7e0a05415f057edb3991\",\"name\":\"donnarossa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/donnarossa.ch\\\/wordpress\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/Portrait-quadrat.jpg\",\"url\":\"https:\\\/\\\/donnarossa.ch\\\/wordpress\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/Portrait-quadrat.jpg\",\"contentUrl\":\"https:\\\/\\\/donnarossa.ch\\\/wordpress\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/Portrait-quadrat.jpg\",\"width\":1000,\"height\":1000,\"caption\":\"donnarossa\"},\"logo\":{\"@id\":\"https:\\\/\\\/donnarossa.ch\\\/wordpress\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/Portrait-quadrat.jpg\"},\"url\":\"https:\\\/\\\/donnarossa.ch\\\/de\\\/author\\\/donnarossa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mein erster Auftrag: eine M\u00fctze f\u00fcr den Bundesrat \u2013 DONNAROSSA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/donnarossa.ch\/de\/mein-erster-auftrag-eine-mutze-fur-den-bundesrat\/","og_locale":"de_DE","og_type":"article","og_title":"Mein erster Auftrag: eine M\u00fctze f\u00fcr den Bundesrat \u2013 DONNAROSSA","og_description":"Wo findet man eine M\u00fctze mit einem speziellen Motiv? L\u00e4sst man das Motiv professionell sticken? Oder die M\u00fctze sogar bedrucken? Hier zeigen sich die Vorteile von Handgemachtem: Man kann das &hellip; Weiterlesen","og_url":"https:\/\/donnarossa.ch\/de\/mein-erster-auftrag-eine-mutze-fur-den-bundesrat\/","og_site_name":"DONNAROSSA","article_published_time":"2016-12-04T09:50:14+00:00","og_image":[{"url":"https:\/\/donnarossa.ch\/wordpress\/wp-content\/uploads\/2016\/11\/WASA-hat.jpg","type":"","width":"","height":""}],"author":"donnarossa","twitter_misc":{"Verfasst von":"donnarossa","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/donnarossa.ch\/de\/mein-erster-auftrag-eine-mutze-fur-den-bundesrat\/#article","isPartOf":{"@id":"https:\/\/donnarossa.ch\/de\/mein-erster-auftrag-eine-mutze-fur-den-bundesrat\/"},"author":{"name":"donnarossa","@id":"https:\/\/donnarossa.ch\/de\/#\/schema\/person\/84a2f974884e7e0a05415f057edb3991"},"headline":"Mein erster Auftrag: eine M\u00fctze f\u00fcr den Bundesrat","datePublished":"2016-12-04T09:50:14+00:00","mainEntityOfPage":{"@id":"https:\/\/donnarossa.ch\/de\/mein-erster-auftrag-eine-mutze-fur-den-bundesrat\/"},"wordCount":376,"commentCount":0,"publisher":{"@id":"https:\/\/donnarossa.ch\/de\/#\/schema\/person\/84a2f974884e7e0a05415f057edb3991"},"image":{"@id":"https:\/\/donnarossa.ch\/de\/mein-erster-auftrag-eine-mutze-fur-den-bundesrat\/#primaryimage"},"thumbnailUrl":"https:\/\/donnarossa.ch\/wordpress\/wp-content\/uploads\/2016\/11\/WASA-hat.jpg","articleSection":["Fertige Objekte"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/donnarossa.ch\/de\/mein-erster-auftrag-eine-mutze-fur-den-bundesrat\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/donnarossa.ch\/de\/mein-erster-auftrag-eine-mutze-fur-den-bundesrat\/","url":"https:\/\/donnarossa.ch\/de\/mein-erster-auftrag-eine-mutze-fur-den-bundesrat\/","name":"Mein erster Auftrag: eine M\u00fctze f\u00fcr den Bundesrat \u2013 DONNAROSSA","isPartOf":{"@id":"https:\/\/donnarossa.ch\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/donnarossa.ch\/de\/mein-erster-auftrag-eine-mutze-fur-den-bundesrat\/#primaryimage"},"image":{"@id":"https:\/\/donnarossa.ch\/de\/mein-erster-auftrag-eine-mutze-fur-den-bundesrat\/#primaryimage"},"thumbnailUrl":"https:\/\/donnarossa.ch\/wordpress\/wp-content\/uploads\/2016\/11\/WASA-hat.jpg","datePublished":"2016-12-04T09:50:14+00:00","breadcrumb":{"@id":"https:\/\/donnarossa.ch\/de\/mein-erster-auftrag-eine-mutze-fur-den-bundesrat\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/donnarossa.ch\/de\/mein-erster-auftrag-eine-mutze-fur-den-bundesrat\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/donnarossa.ch\/de\/mein-erster-auftrag-eine-mutze-fur-den-bundesrat\/#primaryimage","url":"https:\/\/donnarossa.ch\/wordpress\/wp-content\/uploads\/2016\/11\/WASA-hat.jpg","contentUrl":"https:\/\/donnarossa.ch\/wordpress\/wp-content\/uploads\/2016\/11\/WASA-hat.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/donnarossa.ch\/de\/mein-erster-auftrag-eine-mutze-fur-den-bundesrat\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/donnarossa.ch\/de\/"},{"@type":"ListItem","position":2,"name":"Mein erster Auftrag: eine M\u00fctze f\u00fcr den Bundesrat"}]},{"@type":"WebSite","@id":"https:\/\/donnarossa.ch\/de\/#website","url":"https:\/\/donnarossa.ch\/de\/","name":"DONNAROSSA","description":"Strickanleitungen &amp; Workshops f\u00fcr die moderne Macherin","publisher":{"@id":"https:\/\/donnarossa.ch\/de\/#\/schema\/person\/84a2f974884e7e0a05415f057edb3991"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/donnarossa.ch\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":["Person","Organization"],"@id":"https:\/\/donnarossa.ch\/de\/#\/schema\/person\/84a2f974884e7e0a05415f057edb3991","name":"donnarossa","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/donnarossa.ch\/wordpress\/wp-content\/uploads\/2021\/04\/Portrait-quadrat.jpg","url":"https:\/\/donnarossa.ch\/wordpress\/wp-content\/uploads\/2021\/04\/Portrait-quadrat.jpg","contentUrl":"https:\/\/donnarossa.ch\/wordpress\/wp-content\/uploads\/2021\/04\/Portrait-quadrat.jpg","width":1000,"height":1000,"caption":"donnarossa"},"logo":{"@id":"https:\/\/donnarossa.ch\/wordpress\/wp-content\/uploads\/2021\/04\/Portrait-quadrat.jpg"},"url":"https:\/\/donnarossa.ch\/de\/author\/donnarossa\/"}]}},"_links":{"self":[{"href":"https:\/\/donnarossa.ch\/de\/wp-json\/wp\/v2\/posts\/12258","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/donnarossa.ch\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/donnarossa.ch\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/donnarossa.ch\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/donnarossa.ch\/de\/wp-json\/wp\/v2\/comments?post=12258"}],"version-history":[{"count":0,"href":"https:\/\/donnarossa.ch\/de\/wp-json\/wp\/v2\/posts\/12258\/revisions"}],"wp:attachment":[{"href":"https:\/\/donnarossa.ch\/de\/wp-json\/wp\/v2\/media?parent=12258"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/donnarossa.ch\/de\/wp-json\/wp\/v2\/categories?post=12258"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/donnarossa.ch\/de\/wp-json\/wp\/v2\/tags?post=12258"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}