{"id":454,"count":1,"description":"","link":"https:\/\/donnarossa.ch\/de\/tag\/how-to-de\/","name":"how to","slug":"how-to-de","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>how to Archives &#8226; DONNAROSSA<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"how to Archives &#8226; DONNAROSSA\" \/>\n<meta property=\"og:url\" content=\"https:\/\/donnarossa.ch\/de\/tag\/how-to-de\/\" \/>\n<meta property=\"og:site_name\" content=\"DONNAROSSA\" \/>\n<meta property=\"og:image\" content=\"https:\/\/donnarossa.ch\/wordpress\/wp-content\/uploads\/2019\/04\/Logo-sw.png\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"117\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/donnarossa.ch\\\/de\\\/tag\\\/how-to-de\\\/\",\"url\":\"https:\\\/\\\/donnarossa.ch\\\/de\\\/tag\\\/how-to-de\\\/\",\"name\":\"how to Archives &#8226; DONNAROSSA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/donnarossa.ch\\\/de\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/donnarossa.ch\\\/de\\\/tag\\\/how-to-de\\\/#breadcrumb\"},\"inLanguage\":\"de\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/donnarossa.ch\\\/de\\\/tag\\\/how-to-de\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/donnarossa.ch\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"how to\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/donnarossa.ch\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/donnarossa.ch\\\/de\\\/\",\"name\":\"DONNAROSSA\",\"description\":\"Strickanleitungen &amp; Workshops f\u00fcr die moderne Macherin\",\"publisher\":{\"@id\":\"https:\\\/\\\/donnarossa.ch\\\/de\\\/#\\\/schema\\\/person\\\/84a2f974884e7e0a05415f057edb3991\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/donnarossa.ch\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/donnarossa.ch\\\/de\\\/#\\\/schema\\\/person\\\/84a2f974884e7e0a05415f057edb3991\",\"name\":\"donnarossa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/donnarossa.ch\\\/wordpress\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/Portrait-quadrat.jpg\",\"url\":\"https:\\\/\\\/donnarossa.ch\\\/wordpress\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/Portrait-quadrat.jpg\",\"contentUrl\":\"https:\\\/\\\/donnarossa.ch\\\/wordpress\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/Portrait-quadrat.jpg\",\"width\":1000,\"height\":1000,\"caption\":\"donnarossa\"},\"logo\":{\"@id\":\"https:\\\/\\\/donnarossa.ch\\\/wordpress\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/Portrait-quadrat.jpg\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"how to Archives &#8226; DONNAROSSA","robots":{"index":"noindex","follow":"follow"},"og_locale":"de_DE","og_type":"article","og_title":"how to Archives &#8226; DONNAROSSA","og_url":"https:\/\/donnarossa.ch\/de\/tag\/how-to-de\/","og_site_name":"DONNAROSSA","og_image":[{"width":600,"height":117,"url":"https:\/\/donnarossa.ch\/wordpress\/wp-content\/uploads\/2019\/04\/Logo-sw.png","type":"image\/png"}],"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/donnarossa.ch\/de\/tag\/how-to-de\/","url":"https:\/\/donnarossa.ch\/de\/tag\/how-to-de\/","name":"how to Archives &#8226; DONNAROSSA","isPartOf":{"@id":"https:\/\/donnarossa.ch\/de\/#website"},"breadcrumb":{"@id":"https:\/\/donnarossa.ch\/de\/tag\/how-to-de\/#breadcrumb"},"inLanguage":"de"},{"@type":"BreadcrumbList","@id":"https:\/\/donnarossa.ch\/de\/tag\/how-to-de\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/donnarossa.ch\/de\/"},{"@type":"ListItem","position":2,"name":"how to"}]},{"@type":"WebSite","@id":"https:\/\/donnarossa.ch\/de\/#website","url":"https:\/\/donnarossa.ch\/de\/","name":"DONNAROSSA","description":"Strickanleitungen &amp; Workshops f\u00fcr die moderne Macherin","publisher":{"@id":"https:\/\/donnarossa.ch\/de\/#\/schema\/person\/84a2f974884e7e0a05415f057edb3991"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/donnarossa.ch\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":["Person","Organization"],"@id":"https:\/\/donnarossa.ch\/de\/#\/schema\/person\/84a2f974884e7e0a05415f057edb3991","name":"donnarossa","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/donnarossa.ch\/wordpress\/wp-content\/uploads\/2021\/04\/Portrait-quadrat.jpg","url":"https:\/\/donnarossa.ch\/wordpress\/wp-content\/uploads\/2021\/04\/Portrait-quadrat.jpg","contentUrl":"https:\/\/donnarossa.ch\/wordpress\/wp-content\/uploads\/2021\/04\/Portrait-quadrat.jpg","width":1000,"height":1000,"caption":"donnarossa"},"logo":{"@id":"https:\/\/donnarossa.ch\/wordpress\/wp-content\/uploads\/2021\/04\/Portrait-quadrat.jpg"}}]}},"_links":{"self":[{"href":"https:\/\/donnarossa.ch\/de\/wp-json\/wp\/v2\/tags\/454","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/donnarossa.ch\/de\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/donnarossa.ch\/de\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/donnarossa.ch\/de\/wp-json\/wp\/v2\/posts?tags=454"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}